{"id":428,"count":1,"description":"","link":"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/","name":"practicas ancestrales","slug":"practicas-ancestrales","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>practicas ancestrales archivos - PachaMamita Ecuador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"practicas ancestrales archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/\" \/>\n<meta property=\"og:site_name\" content=\"PachaMamita Ecuador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/category\\\/practicas-ancestrales\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/category\\\/practicas-ancestrales\\\/\",\"name\":\"practicas ancestrales archivos - PachaMamita Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/category\\\/practicas-ancestrales\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/category\\\/practicas-ancestrales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"practicas ancestrales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"name\":\"PachaMamita Ecuador\",\"description\":\"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\",\"name\":\"PachaMamita Ecuador\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"width\":512,\"height\":512,\"caption\":\"PachaMamita Ecuador\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pachamamitaecu\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"practicas ancestrales archivos - PachaMamita Ecuador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/","og_locale":"es_ES","og_type":"article","og_title":"practicas ancestrales archivos","og_url":"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/","og_site_name":"PachaMamita Ecuador","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/","url":"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/","name":"practicas ancestrales archivos - PachaMamita Ecuador","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#website"},"breadcrumb":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/pachamamitaecu.org\/es_es\/category\/practicas-ancestrales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pachamamitaecu.org\/es_es\/"},{"@type":"ListItem","position":2,"name":"practicas ancestrales"}]},{"@type":"WebSite","@id":"https:\/\/pachamamitaecu.org\/es_es\/#website","url":"https:\/\/pachamamitaecu.org\/es_es\/","name":"PachaMamita Ecuador","description":"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.","publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pachamamitaecu.org\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization","name":"PachaMamita Ecuador","url":"https:\/\/pachamamitaecu.org\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","width":512,"height":512,"caption":"PachaMamita Ecuador"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pachamamitaecu"]}]}},"_links":{"self":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories\/428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts?categories=428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}