{"id":1103,"date":"2011-11-13T10:49:00","date_gmt":"2011-11-13T10:49:00","guid":{"rendered":"http:\/\/pachamamitaecu-org-720647.hostingersite.com\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/"},"modified":"2024-05-26T12:58:35","modified_gmt":"2024-05-26T12:58:35","slug":"gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais","status":"publish","type":"post","link":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/","title":{"rendered":"Gobierno en conversaciones con la \u00abPeor Compa\u00f1\u00eda del Mundo\u00bb, interesada en venir al pa\u00eds."},"content":{"rendered":"<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" data-src=\"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" \/><\/a><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">El bolet\u00edn de prensa 614 del mes de junio del 2011 del Ministerio de Relaciones Exteriores, Comercio e Integraci\u00f3n del Ecuador, que cita que \u00abdelegados del Ministerio de Recursos Naturales No Renovables y directivos de InvestEcuador&#8230;, concluyeron con una visita en Sud\u00e1frica (y) cumplieron una agenda con empresas mineras como Mponeng, propiedad de AngloGold Ashanti\u00bb sonar\u00eda de primera mano como una noticia interesante para quienes defienden la Miner\u00eda a Gran Escala en el Ecuador; sobre todo, si al seguir leyendo la noticia podemos encontrar que : \u00bb El Viceministro, Federico Auquilla asegur\u00f3 que (durante) la visita de la delegaci\u00f3n ecuatoriana \u201chemos identificado soluciones tecnol\u00f3gicas para la miner\u00eda mediana y artesanal as\u00ed como para la reducci\u00f3n de los impactos ambientales en los procesos mineros a peque\u00f1a, mediana y gran escala\u201d. Esto antes de mencionar nuevamente a AngloGold Ashanti y otras 21 empresas del sector.<\/span><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Sin embargo al momento de realizar cruce de informaci\u00f3n, resulta que s\u00f3lo meses atr\u00e1s, dicha compa\u00f1ia hab\u00eda sido galardonada con el \u00abdesprestigioso\u00bb Premio \u00abOjo P\u00fablico\u00bb 2011 como la \u00abPeor Empresa del Mundo\u00bb, por&nbsp;su responsabilidad en el envenenamiento de &nbsp;tierras y &nbsp;r\u00edos en sus procesos de extracci\u00f3n de oro en Ghana. Durante la entrega de los premios, el Director de la Asociaci\u00f3n de V\u00edctimas del Envenenamiento de Ghana,&nbsp;Owusu Koranteng, , denunci\u00f3 &nbsp;que AngloGold\/Ashanti no ha hecho nada para evitar los recurrentes vertidos de substancias t\u00f3xicas, que han contaminado las fuentes de agua potable de vastas regiones; y que&nbsp;varias personas han sido v\u00edctimas de tortura a manos de agentes de seguridad empleados de la &nbsp;minera.<\/span><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Mientras tanto en la vecina Colombia; donde AngloGold\/Ashanti tiene presencia con&nbsp;<span style=\"background-color: white; color: #333333; line-height: 23px;\">&nbsp;<\/span>el proyecto de la mina de oro La Colosa en  Cajamarca (en la regi\u00f3n andina), el Observatorio de Conflictos Mineros de Am\u00e9rica Latina describe que : &nbsp;\u00abOrganizaciones internacionales han documentado el compromiso de la AngloGold                Ashant\u00ed (AGA) con estructuras armadas y cr\u00edmenes ejecutados en diferentes pa\u00edses, a&nbsp;fin de garantizar su ingreso y el desarrollo de explotaciones en gran escala. Diferentes&nbsp;denuncias de organizaciones sociales y de Derechos Humanos (DDHH) en Colombia&nbsp;han demostrado que la situaci\u00f3n en el pa\u00eds, especialmente en el Sur de Bol\u00edvar,&nbsp;parece responder a patrones similares.\u00bb<\/span><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div><div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">El bolet\u00edn del MRECI (Ecuador) finaliza anunciando la \u00abbuena noticia\u00bb de que en este \u00faltimo semestre mediante visitas sudafricanas al pa\u00eds se avanzar\u00eda \u00aben el orden comercial\u00bb con &nbsp;las empresas del sector.&nbsp;<\/span><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div><div style=\"text-align: justify;\"><div><span style=\"font-family: Georgia, Times New Roman, serif;\">Las votaciones de los premios \u00abOjo P\u00fablico\u00bb reunieron m\u00e1s de 50,000 personas quienes votaron online y marcan un contrapunto cr\u00edtico al encuentro anual del Foro Econ\u00f3mico Mundial in Davos. Es organizado desde el a\u00f1o 2000 por la Declaraci\u00f3n de Berna, y Amigos de la Tierra (en el 2009 reemplazada por Greenpeace), Los Premios \u00abOjo P\u00fablico\u00bb recuerdan a las corporaciones del mundo que sus omisiones en materia social y ambiental tienen consecuencias para la gente afectada y sus territorios pero tambi\u00e9n para la reputaci\u00f3n del ofensor.<\/span><br \/><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div><\/div><div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><b><u>Fuentes:<\/u><\/b><\/span><\/div><\/div><div><ul><li style=\"text-align: justify;\"><a href=\"http:\/\/www.mmrree.gob.ec\/2011\/bol614.asp\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Bolet\u00edn 614. Ministerio de Relaciones Exteriores Comercio e Integraci\u00f3n del Ecuador&nbsp;<\/span><\/a><\/li><li style=\"text-align: justify;\"><a href=\"http:\/\/justiciaypazcolombia.com\/AngloGold-Ashanti-y-Neste-Oil\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Comisi\u00f3n Interclesial de Justicia y Paz (Colombia)<\/span><\/a><\/li><li style=\"text-align: justify;\"><a href=\"http:\/\/www.olca.cl\/ocmal\/ds_conf.php?nota=Conflicto&amp;p_busca=76\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Observatorio de Conflictos Mineros en Am\u00e9rica Latina<\/span><\/a><\/li><li style=\"text-align: justify;\"><a href=\"http:\/\/www.publiceye.ch\/en\/\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Public Eye Awards<\/span><\/a><\/li><\/ul><\/div><div class=\"pvc_clear\"><\/div><p id=\"pvc_stats_1103\" class=\"pvc_stats total_only  \" data-element-id=\"1103\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/pachamamitaecu.org\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p><div class=\"pvc_clear\"><\/div>","protected":false},"excerpt":{"rendered":"<p>El bolet\u00edn de prensa 614 del mes de junio del 2011 del Ministerio de Relaciones Exteriores, Comercio e Integraci\u00f3n del Ecuador, que cita que \u00abdelegados del Ministerio de Recursos Naturales No Renovables y directivos de InvestEcuador&#8230;, concluyeron con una visita en Sud\u00e1frica (y) cumplieron una agenda con empresas mineras como Mponeng, propiedad de AngloGold Ashanti\u00bb [&#8230;]\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[159,280,264],"tags":[],"class_list":["post-1103","post","type-post","status-publish","format-standard","hentry","category-consumo-responsable","category-mineria","category-noticias"],"a3_pvc":{"activated":true,"total_views":27,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gobierno en conversaciones con la &quot;Peor Compa\u00f1\u00eda del Mundo&quot;, interesada en venir al pa\u00eds. - PachaMamita Ecuador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno en conversaciones con la &quot;Peor Compa\u00f1\u00eda del Mundo&quot;, interesada en venir al pa\u00eds.\" \/>\n<meta property=\"og:description\" content=\"El bolet\u00edn de prensa 614 del mes de junio del 2011 del Ministerio de Relaciones Exteriores, Comercio e Integraci\u00f3n del Ecuador, que cita que \u00abdelegados del Ministerio de Recursos Naturales No Renovables y directivos de InvestEcuador&#8230;, concluyeron con una visita en Sud\u00e1frica (y) cumplieron una agenda con empresas mineras como Mponeng, propiedad de AngloGold Ashanti\u00bb [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"PachaMamita Ecuador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pachamamitaecu\" \/>\n<meta property=\"article:published_time\" content=\"2011-11-13T10:49:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-26T12:58:35+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg\" \/>\n<meta name=\"author\" content=\"PachaMamita EC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PachaMamita EC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/\"},\"author\":{\"name\":\"PachaMamita EC\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\"},\"headline\":\"Gobierno en conversaciones con la \u00abPeor Compa\u00f1\u00eda del Mundo\u00bb, interesada en venir al pa\u00eds.\",\"datePublished\":\"2011-11-13T10:49:00+00:00\",\"dateModified\":\"2024-05-26T12:58:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/\"},\"wordCount\":575,\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-6gFCa59orS4\\\/Tr-fxNYzBSI\\\/AAAAAAAABiw\\\/Wqauk28Ze7Y\\\/s1600\\\/bol614_2011.jpg\",\"articleSection\":[\"CONSUMO RESPONSABLE\",\"mineria\",\"noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/\",\"name\":\"Gobierno en conversaciones con la \\\"Peor Compa\u00f1\u00eda del Mundo\\\", interesada en venir al pa\u00eds. - PachaMamita Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-6gFCa59orS4\\\/Tr-fxNYzBSI\\\/AAAAAAAABiw\\\/Wqauk28Ze7Y\\\/s1600\\\/bol614_2011.jpg\",\"datePublished\":\"2011-11-13T10:49:00+00:00\",\"dateModified\":\"2024-05-26T12:58:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/#primaryimage\",\"url\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-6gFCa59orS4\\\/Tr-fxNYzBSI\\\/AAAAAAAABiw\\\/Wqauk28Ze7Y\\\/s1600\\\/bol614_2011.jpg\",\"contentUrl\":\"http:\\\/\\\/1.bp.blogspot.com\\\/-6gFCa59orS4\\\/Tr-fxNYzBSI\\\/AAAAAAAABiw\\\/Wqauk28Ze7Y\\\/s1600\\\/bol614_2011.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/11\\\/13\\\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno en conversaciones con la \u00abPeor Compa\u00f1\u00eda del Mundo\u00bb, interesada en venir al pa\u00eds.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"name\":\"PachaMamita Ecuador\",\"description\":\"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\",\"name\":\"PachaMamita Ecuador\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"width\":512,\"height\":512,\"caption\":\"PachaMamita Ecuador\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pachamamitaecu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\",\"name\":\"PachaMamita EC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"PachaMamita EC\"},\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/author\\\/pachamamita-ec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gobierno en conversaciones con la \"Peor Compa\u00f1\u00eda del Mundo\", interesada en venir al pa\u00eds. - PachaMamita Ecuador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno en conversaciones con la \"Peor Compa\u00f1\u00eda del Mundo\", interesada en venir al pa\u00eds.","og_description":"El bolet\u00edn de prensa 614 del mes de junio del 2011 del Ministerio de Relaciones Exteriores, Comercio e Integraci\u00f3n del Ecuador, que cita que \u00abdelegados del Ministerio de Recursos Naturales No Renovables y directivos de InvestEcuador&#8230;, concluyeron con una visita en Sud\u00e1frica (y) cumplieron una agenda con empresas mineras como Mponeng, propiedad de AngloGold Ashanti\u00bb [...]","og_url":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/","og_site_name":"PachaMamita Ecuador","article_publisher":"https:\/\/www.facebook.com\/pachamamitaecu","article_published_time":"2011-11-13T10:49:00+00:00","article_modified_time":"2024-05-26T12:58:35+00:00","og_image":[{"url":"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg","type":"","width":"","height":""}],"author":"PachaMamita EC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PachaMamita EC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/#article","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/"},"author":{"name":"PachaMamita EC","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593"},"headline":"Gobierno en conversaciones con la \u00abPeor Compa\u00f1\u00eda del Mundo\u00bb, interesada en venir al pa\u00eds.","datePublished":"2011-11-13T10:49:00+00:00","dateModified":"2024-05-26T12:58:35+00:00","mainEntityOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/"},"wordCount":575,"publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg","articleSection":["CONSUMO RESPONSABLE","mineria","noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/","url":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/","name":"Gobierno en conversaciones con la \"Peor Compa\u00f1\u00eda del Mundo\", interesada en venir al pa\u00eds. - PachaMamita Ecuador","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/#primaryimage"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/#primaryimage"},"thumbnailUrl":"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg","datePublished":"2011-11-13T10:49:00+00:00","dateModified":"2024-05-26T12:58:35+00:00","breadcrumb":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/#primaryimage","url":"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg","contentUrl":"http:\/\/1.bp.blogspot.com\/-6gFCa59orS4\/Tr-fxNYzBSI\/AAAAAAAABiw\/Wqauk28Ze7Y\/s1600\/bol614_2011.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/11\/13\/gobierno-en-conversaciones-con-la-peor-compania-del-mundo-interesada-en-venir-al-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pachamamitaecu.org\/es_es\/"},{"@type":"ListItem","position":2,"name":"Gobierno en conversaciones con la \u00abPeor Compa\u00f1\u00eda del Mundo\u00bb, interesada en venir al pa\u00eds."}]},{"@type":"WebSite","@id":"https:\/\/pachamamitaecu.org\/es_es\/#website","url":"https:\/\/pachamamitaecu.org\/es_es\/","name":"PachaMamita Ecuador","description":"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.","publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pachamamitaecu.org\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization","name":"PachaMamita Ecuador","url":"https:\/\/pachamamitaecu.org\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","width":512,"height":512,"caption":"PachaMamita Ecuador"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pachamamitaecu"]},{"@type":"Person","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593","name":"PachaMamita EC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"PachaMamita EC"},"url":"https:\/\/pachamamitaecu.org\/es_es\/author\/pachamamita-ec\/"}]}},"_links":{"self":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/comments?post=1103"}],"version-history":[{"count":1,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1103\/revisions"}],"predecessor-version":[{"id":3063,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1103\/revisions\/3063"}],"wp:attachment":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/media?parent=1103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories?post=1103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/tags?post=1103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}