{"id":1165,"date":"2011-09-26T23:21:00","date_gmt":"2011-09-26T23:21:00","guid":{"rendered":"http:\/\/pachamamitaecu-org-720647.hostingersite.com\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/"},"modified":"2023-03-01T15:27:48","modified_gmt":"2023-03-01T15:27:48","slug":"gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia","status":"publish","type":"post","link":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/","title":{"rendered":"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia."},"content":{"rendered":"<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s1600\/n1219033490_1513082_5995156.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"320\" data-src=\"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s320\/n1219033490_1513082_5995156.jpg\" width=\"308\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 308px; --smush-placeholder-aspect-ratio: 308\/320;\" \/><\/a><\/div>\n<p><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">El gobierno ecuatoriano  anunci\u00f3, en septiembre del 2010, sus planes de ampliar la frontera petrolera hacia el suroriente del pa\u00eds. D\u00edas atr\u00e1s esa pretensi\u00f3n avanz\u00f3 al hacer el anuncio oficial de que el 31 de octubre se lanzar\u00e1 otra convocatoria, esta vez para los bloques surorientales. Las ofertas deber\u00e1n presentarse hasta el 1 de abril del pr\u00f3ximo a\u00f1o para firmar los contratos respectivos en octubre del 2012, seg\u00fan un comunicado del Ministerio de Energ\u00edas no Renovables.&nbsp;De los bloques que se ofrecer\u00e1n en el nuevo proceso, cuatro pasar\u00e1n a manos de las estatales Petroamazonas y Petroecuador, siete se asignar\u00e1n a petroleras nacionales de pa\u00edses \u00abamigos\u00bb, y 10 se entregar\u00e1n a firmas privadas, agreg\u00f3 la cartera.&nbsp;<\/span><\/p>\n<div><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Los bloques petroleros en el centro sur que se negocian en la nueva ronda  superponen territorios de las nacionalidades ind\u00edgenas: achuar, s\u00e1para, shiwiar, andoa, shuar y kichwa y suponen un \u00e1rea de casi dos veces y media m\u00e1s grande que el proyecto ITT Yasun\u00ed.<\/span><\/div>\n<div><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Ante esta nueva ronda, los pueblos ind\u00edgenas amaz\u00f3nicos, quienes la consideran una amenaza que se viene sobre ellos, se reunieron , se declararon en resistencia&nbsp;<\/span><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">(el \u00abderecho a la resistencia\u00bb est\u00e1 referido al art\u00edculo 98 de la Constituci\u00f3n: \u00ablos individuos y los colectivos podr\u00e1n ejercer el derecho a la resistencia frente a acciones u omisiones del poder p\u00fablico o de las personas naturales o jur\u00eddicas no estatales que vulneren o puedan vulnerar sus derechos constitucionales, y demandar el reconocimiento de nuevos derechos\u00bb) por lo que <\/span><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">firmaron la siguiente Declaratoria:<\/span><\/div>\n<div><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/>Declaratoria  del Cuarto Encuentro de nacionalidades Achuar, Shuar y Kichwa de la Regi\u00f3n Amaz\u00f3nica Ecuatoriana en Resistencia por defensa de la Vida.<br \/><\/span><\/div>\n<div><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><\/span><\/p>\n<ul>\n<li><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Las nacionalidades Achuar, Shuar y Kichwa de la provincia de Pastaza y Morona Santiago, declaran en Estado de emergencia en sus territorios, por la invasi\u00f3n inconsulta de la d\u00e9cima ronda petrolera, minera, servicios ambientales y bio-prospecci\u00f3n, que atenta gravemente sus espacios de vida y sus derechos reconocidos y consagrados en la constituci\u00f3n pol\u00edtica del Estado, convenios y tratados internacionales que amparan y protegen los derechos de las nacionalidades ind\u00edgenas.<\/span><\/li>\n<p><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><\/p>\n<li>Se comprometen en llevar una lucha pac\u00edfica y soberana hasta las \u00faltimas consecuencias, decididos enfrentar hasta con sus vidas para defender la madre tierra que es el \u00fanico espacio de vida.&nbsp;<\/li>\n<li>Hacen un llamado a todo los hermanos de otras nacionalidades y pueblos que \u00e9ste es el momento de demostrar la verdadera unidad en defensa de los territorios de esa forma construir el verdadero Sumak Kawsay- Penker Pujustin (Buen  Vivir).<\/li>\n<li>Piden a los otros pueblos y nacionalidades hermanos de otros continentes y a la comunidad internacional que sean testigos de todas las violaciones de los derechos de las nacionalidades, que el gobierno de Ecuador ha implementado para defender los intereses de las empresas extractivas transnacionales.&nbsp;<\/li>\n<li>Rechazan a todas las personas ilegales que hacen pasar como profesionales y representantes legales de los pueblos y nacionalidades, ofreciendo servicio profesionales de relacionadores comunitarios, quienes ser\u00e1n severamente sancionados y castigados con la ley ancestral de cada nacionalidad.<\/li>\n<p><\/span><\/ul>\n<p><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Mientras tanto, la CONAIE, la m\u00e1s grande e importante organizaci\u00f3n ind\u00edgena del pa\u00eds anuncia una marcha a Quito para exigir que sea aplicada la consulta previa, que aunque est\u00e1 estipulada en la Constituci\u00f3n del 98 y ratificada en la del 2008, no es aplicada, seg\u00fan el Procurador del Estado porque no existe norma infraconstitucional. <\/p>\n<p>La fecha de la movilizaci\u00f3n a\u00fan no est\u00e1 definida y se tomar\u00e1n \u00abel tiempo que sea necesario para organizar\u00bb a las comunidades, dijo Cholango, presidente de la Confederaci\u00f3n de Nacionalidades Ind\u00edgenas del Ecuador (Conaie), al diario Expreso.<\/p>\n<p>\u00abHay que repetir, parafraseando al presidente (Rafael Correa): nada por imposici\u00f3n, nada por la fuerza con los pueblos ind\u00edgenas porque si no el conflicto ser\u00e1 de largo tiempo y muy doloroso para los ecuatorianos. Hay que resolver los conflictos mediante mecanismos inteligentes\u00bb, afirm\u00f3 Cholango.<\/p>\n<p>El mandatario enfrenta la oposici\u00f3n de la Conaie, un antiguo aliado que en marzo lo denunci\u00f3 penalmente por genocidio aduciendo que ha alentado la explotaci\u00f3n petrolera en sus tierras.<\/span><\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_1165\" class=\"pvc_stats total_only  \" data-element-id=\"1165\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/pachamamitaecu.org\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno ecuatoriano anunci\u00f3, en septiembre del 2010, sus planes de ampliar la frontera petrolera hacia el suroriente del pa\u00eds. D\u00edas atr\u00e1s esa pretensi\u00f3n avanz\u00f3 al hacer el anuncio oficial de que el 31 de octubre se lanzar\u00e1 otra convocatoria, esta vez para los bloques surorientales. Las ofertas deber\u00e1n presentarse hasta el 1 de abril [&#8230;]\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[159,264],"tags":[],"class_list":["post-1165","post","type-post","status-publish","format-standard","hentry","category-consumo-responsable","category-noticias"],"a3_pvc":{"activated":true,"total_views":32,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia. - PachaMamita Ecuador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia.\" \/>\n<meta property=\"og:description\" content=\"El gobierno ecuatoriano anunci\u00f3, en septiembre del 2010, sus planes de ampliar la frontera petrolera hacia el suroriente del pa\u00eds. D\u00edas atr\u00e1s esa pretensi\u00f3n avanz\u00f3 al hacer el anuncio oficial de que el 31 de octubre se lanzar\u00e1 otra convocatoria, esta vez para los bloques surorientales. Las ofertas deber\u00e1n presentarse hasta el 1 de abril [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/\" \/>\n<meta property=\"og:site_name\" content=\"PachaMamita Ecuador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pachamamitaecu\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-26T23:21:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T15:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s320\/n1219033490_1513082_5995156.jpg\" \/>\n<meta name=\"author\" content=\"PachaMamita EC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PachaMamita EC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/\"},\"author\":{\"name\":\"PachaMamita EC\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\"},\"headline\":\"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia.\",\"datePublished\":\"2011-09-26T23:21:00+00:00\",\"dateModified\":\"2023-03-01T15:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/\"},\"wordCount\":715,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/-1X3KOh3yql4\\\/ToEFz8T7qpI\\\/AAAAAAAABXY\\\/uq06ar9I2Ck\\\/s320\\\/n1219033490_1513082_5995156.jpg\",\"articleSection\":[\"CONSUMO RESPONSABLE\",\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/\",\"name\":\"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia. - PachaMamita Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/-1X3KOh3yql4\\\/ToEFz8T7qpI\\\/AAAAAAAABXY\\\/uq06ar9I2Ck\\\/s320\\\/n1219033490_1513082_5995156.jpg\",\"datePublished\":\"2011-09-26T23:21:00+00:00\",\"dateModified\":\"2023-03-01T15:27:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#primaryimage\",\"url\":\"http:\\\/\\\/4.bp.blogspot.com\\\/-1X3KOh3yql4\\\/ToEFz8T7qpI\\\/AAAAAAAABXY\\\/uq06ar9I2Ck\\\/s320\\\/n1219033490_1513082_5995156.jpg\",\"contentUrl\":\"http:\\\/\\\/4.bp.blogspot.com\\\/-1X3KOh3yql4\\\/ToEFz8T7qpI\\\/AAAAAAAABXY\\\/uq06ar9I2Ck\\\/s320\\\/n1219033490_1513082_5995156.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2011\\\/09\\\/26\\\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"name\":\"PachaMamita Ecuador\",\"description\":\"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\",\"name\":\"PachaMamita Ecuador\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"width\":512,\"height\":512,\"caption\":\"PachaMamita Ecuador\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pachamamitaecu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\",\"name\":\"PachaMamita EC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"PachaMamita EC\"},\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/author\\\/pachamamita-ec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia. - PachaMamita Ecuador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia.","og_description":"El gobierno ecuatoriano anunci\u00f3, en septiembre del 2010, sus planes de ampliar la frontera petrolera hacia el suroriente del pa\u00eds. D\u00edas atr\u00e1s esa pretensi\u00f3n avanz\u00f3 al hacer el anuncio oficial de que el 31 de octubre se lanzar\u00e1 otra convocatoria, esta vez para los bloques surorientales. Las ofertas deber\u00e1n presentarse hasta el 1 de abril [...]","og_url":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/","og_site_name":"PachaMamita Ecuador","article_publisher":"https:\/\/www.facebook.com\/pachamamitaecu","article_published_time":"2011-09-26T23:21:00+00:00","article_modified_time":"2023-03-01T15:27:48+00:00","og_image":[{"url":"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s320\/n1219033490_1513082_5995156.jpg","type":"","width":"","height":""}],"author":"PachaMamita EC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PachaMamita EC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#article","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/"},"author":{"name":"PachaMamita EC","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593"},"headline":"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia.","datePublished":"2011-09-26T23:21:00+00:00","dateModified":"2023-03-01T15:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/"},"wordCount":715,"commentCount":0,"publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#primaryimage"},"thumbnailUrl":"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s320\/n1219033490_1513082_5995156.jpg","articleSection":["CONSUMO RESPONSABLE","noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/","url":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/","name":"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia. - PachaMamita Ecuador","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#primaryimage"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#primaryimage"},"thumbnailUrl":"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s320\/n1219033490_1513082_5995156.jpg","datePublished":"2011-09-26T23:21:00+00:00","dateModified":"2023-03-01T15:27:48+00:00","breadcrumb":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#primaryimage","url":"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s320\/n1219033490_1513082_5995156.jpg","contentUrl":"http:\/\/4.bp.blogspot.com\/-1X3KOh3yql4\/ToEFz8T7qpI\/AAAAAAAABXY\/uq06ar9I2Ck\/s320\/n1219033490_1513082_5995156.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/pachamamitaecu.org\/es_es\/2011\/09\/26\/gobierno-de-ecuador-anuncia-nueva-ronda-petrolera-nacionalidades-indigenas-se-declaran-en-resistencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pachamamitaecu.org\/es_es\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Ecuador anuncia nueva ronda petrolera. Nacionalidades ind\u00edgenas se declaran en Resistencia."}]},{"@type":"WebSite","@id":"https:\/\/pachamamitaecu.org\/es_es\/#website","url":"https:\/\/pachamamitaecu.org\/es_es\/","name":"PachaMamita Ecuador","description":"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.","publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pachamamitaecu.org\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization","name":"PachaMamita Ecuador","url":"https:\/\/pachamamitaecu.org\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","width":512,"height":512,"caption":"PachaMamita Ecuador"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pachamamitaecu"]},{"@type":"Person","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593","name":"PachaMamita EC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"PachaMamita EC"},"url":"https:\/\/pachamamitaecu.org\/es_es\/author\/pachamamita-ec\/"}]}},"_links":{"self":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/comments?post=1165"}],"version-history":[{"count":0,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1165\/revisions"}],"wp:attachment":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/media?parent=1165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories?post=1165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/tags?post=1165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}