{"id":1197,"date":"2011-08-25T04:09:00","date_gmt":"2011-08-25T04:09:00","guid":{"rendered":"http:\/\/pachamamitaecu-org-720647.hostingersite.com\/2011\/08\/25\/inpc-anuncia-acciones-por-destruccion-patrimonial-en-la-libertad-durante-labores-del-municipio\/"},"modified":"2011-08-25T04:09:00","modified_gmt":"2011-08-25T04:09:00","slug":"inpc-anuncia-acciones-por-destruccion-patrimonial-en-la-libertad-durante-labores-del-municipio","status":"publish","type":"post","link":"https:\/\/pachamamitaecu.org\/es_es\/2011\/08\/25\/inpc-anuncia-acciones-por-destruccion-patrimonial-en-la-libertad-durante-labores-del-municipio\/","title":{"rendered":"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio"},"content":{"rendered":"<table cellpadding=\"0\" cellspacing=\"0\" style=\"float: left; margin-right: 1em; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><a href=\"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s1600\/296583_2237679232207_1554784837_2444431_4248601_n.jpg\" style=\"clear: left; margin-bottom: 1em; margin-left: auto; margin-right: auto;\"><img decoding=\"async\" border=\"0\" height=\"240\" data-src=\"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s320\/296583_2237679232207_1554784837_2444431_4248601_n.jpg\" width=\"320\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 320px; --smush-placeholder-aspect-ratio: 320\/240;\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\">FOTO:<a href=\"http:\/\/www.facebook.com\/profile.php?id=1554784837\"> EL LITORAL<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">El Instituto Nacional de Patrimonio Cultural Direcci\u00f3n Regional 5 ante las declaraciones de ciertos ciudadanos que est\u00e1n escribiendo al portal Facebook de la regional 5 (Patrimonio Vivo) sobre una denuncia que el INPC no ha actuado en respuesta a la salvaguarda del patrimonio cultural de la pen\u00ednsula en cuanto al hallazgo arqueol\u00f3gico realizado en la ciudad de La Libertad en d\u00eda pasados, es necesario realizar las siguientes precisiones:<\/span><\/div>\n<p><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">El pasado lunes 15 de agosto del 2011 al medio d\u00eda en el cant\u00f3n La Libertad, en las calles: Avenida diagonal 1era y calles 15,16 y 17 el Municipio de la Libertad a trav\u00e9s de la Direcci\u00f3n de Obras Publicas se encontraba ejecutando trabajos de repavimentaci\u00f3n de la v\u00eda en el \u00e1rea, por la implementaci\u00f3n de un programa de regeneraci\u00f3n urbana, al paso de la maquinaria se encontraron con un hallazgo arqueol\u00f3gico compuesto de fragmentos de cer\u00e1mica y osamentas humanas correspondientes a la cultura Guancavilca,<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">El mismo lunes 15 de agosto del 2011 en horas de la noche el INPC fue alertado mediante llamada celular por parte de la Dra. Noralma Zambrano, Gobernadora de la Provincia de Santa Elena al Arq. Esteban Delgado de la Cuadra, Director Regional 5 del INPC, quien dispuso inmediatamente una comisi\u00f3n para que viaje y realice un informe pormenorizado de la situaci\u00f3n en el lugar, a su vez la gobernadora manifest\u00f3 que en conjunto con la Abogada Doris Gavilanes; Intendenta de Polic\u00eda hab\u00edan suspendido los trabajos de regeneraci\u00f3n en el lugar,<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<p><\/p>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">La comisi\u00f3n conformada por el Lcdo. Antonio Guillen y la Abg. Carmen Verdezoto, Analista de Riesgos y Vulnerabilidad, y Abogada del INPC DR5 respectivamente, viajaron hasta la ciudad de La Libertad el d\u00eda martes 16 de agosto en horas de la ma\u00f1ana y se trasladaron hasta el lugar de los hechos, en donde al iniciar su inspecci\u00f3n fueron increpados por un grupo de comerciantes del \u00e1rea quienes reclamaron a los t\u00e9cnicos por el impedimento de seguir realizando sus actividades comerciales y laborales  a causa del hallazgo, raz\u00f3n por la cual los t\u00e9cnicos debieron cumplir con su trabajo con peligro y falta de garant\u00edas para el mismo,<\/span><\/div>\n<p><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Es importante mencionar que durante la inspecci\u00f3n realizada el d\u00eda 16 de agosto, estuvieron presentes la Ab. Doris Gavilanes Intendenta de Polic\u00eda, el Ing. Joffre Guti\u00e9rrez Director de Obras P\u00fablicas del Municipio de la Libertad, T\u00e9cnicos del INPC Regional 5, ante la presencia de pobladores y comerciantes del sector,<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">El d\u00eda lunes 15 de agosto el peri\u00f3dico el Litoral en su versi\u00f3n de la red Social Facebook public\u00f3 fotos y comentarios al respecto del tema, generando un debate en donde la ciudadan\u00eda aport\u00f3 al respecto, inmediatamente el INPC procedi\u00f3 a responderle por la misma v\u00eda al Lcdo. Paolo Le\u00f3n Gonzabay, Director del Peri\u00f3dico el Litoral,  explic\u00e1ndole lo que se estaba actuando y que se le enviar\u00eda una copia del informe una vez concluido, ya que fue el quien dio el aviso a las autoridades del hallazgo, mismo que acept\u00f3 el pedido oficial de esta direcci\u00f3n expresando:\u201cCompa\u00f1eros esperar\u00e9 con paciencia, voy a publicar una nota sobre aquello, y ese documento es el oficial que explica que paso con esto, y al igual que ustedes seguiremos buscando proteger nuestro patrimonio para el presente y las futuras generaciones\u2026\u201d.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Los T\u00e9cnicos del INPC no autorizaron  el inicio de trabajos ni la continuaci\u00f3n de las actividades, por lo que el Director de la Regional 5 del INPC est\u00e1 solicitando formalmente la sanci\u00f3n administrativa al responsable,<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Adicionalmente, el INPC llamar\u00e1 la atenci\u00f3n a la Municipalidad de la Libertad por la no contrataci\u00f3n oportuna de los estudios de impacto ambiental, sobre todo el componente arqueol\u00f3gico para determinar presencia o ausencia de vestigios prehisp\u00e1nicos  en la zona previo al inicio de los trabajos, pues toda la pen\u00ednsula est\u00e1 considerada como el sector de mayor riqueza arqueol\u00f3gica del pa\u00eds y no se pueden ejecutar obras p\u00fablicas o privadas sin tener realizados dichos estudios,<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Adem\u00e1s se recuerda a la ciudadan\u00eda en general que  se encuentra vigente la ley vigente de PATRIMONIO CULTURAL DEL ECUADOR y que el C\u00f3digo Penal, en el art\u00edculo N0. 415 A, dice:\u201cEl que destruya o da\u00f1e bienes pertenecientes al Patrimonio Cultural de Naci\u00f3n, ser\u00e1 reprimido con prisi\u00f3n de uno a tres a\u00f1os sin perjuicio de las indemnizaciones debidas a terceros de buena fe y de que el juez, de ser factible, ordene la reconstrucci\u00f3n, restauraci\u00f3n o restituci\u00f3n del bien, a costa del autor de la destrucci\u00f3n o deterioro\u201d,<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">De esta manera el INPC aclara que siempre se est\u00e1n tomando las acciones respectivas en cuanto a las denuncias que llegan hasta esta direcci\u00f3n de hallazgos arqueol\u00f3gicos o destrucci\u00f3n del patrimonio cultural, no solo en el \u00e1mbito local, sino regional y nacional.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">Adem\u00e1s como lo establece el C\u00f3digo Org\u00e1nico de Organizaci\u00f3n Territorial, Autonom\u00eda y Descentralizaci\u00f3n, (COOTAD)  los municipios son responsables del patrimonio de su localidad, y para evitar que los bienes patrimoniales sean vulnerados, el INPC trabaja con los Municipios del pa\u00eds en un programa de capacitaci\u00f3n para que los patrimonios sean recuperados e incorporados a la vida de los ciudadanos.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\">El director regional agradece la permanente y denodada acci\u00f3n comunitaria de la ciudadan\u00eda de la pen\u00ednsula de Santa Elena, que se encuentra permanentemente report\u00e1ndonos este tipo de situaciones, convirti\u00e9ndose en pilar fundamental de la gesti\u00f3n del INPC y que contribuyen desinteresadamente al disfrute, protecci\u00f3n y salvaguarda del patrimonio cultural de la regi\u00f3n y de la naci\u00f3n.<\/span><br \/><span style=\"font-family: Times, 'Times New Roman', serif; font-size: large;\"><br \/><\/span><\/div>\n<p><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_1197\" class=\"pvc_stats total_only  \" data-element-id=\"1197\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/pachamamitaecu.org\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>FOTO: EL LITORAL El Instituto Nacional de Patrimonio Cultural Direcci\u00f3n Regional 5 ante las declaraciones de ciertos ciudadanos que est\u00e1n escribiendo al portal Facebook de la regional 5 (Patrimonio Vivo) sobre una denuncia que el INPC no ha actuado en respuesta a la salvaguarda del patrimonio cultural de la pen\u00ednsula en cuanto al hallazgo arqueol\u00f3gico [&#8230;]\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[264],"tags":[],"class_list":["post-1197","post","type-post","status-publish","format-standard","hentry","category-noticias"],"a3_pvc":{"activated":true,"total_views":41,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio - PachaMamita Ecuador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pachamamitaecu.org\/es_es\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio\" \/>\n<meta property=\"og:description\" content=\"FOTO: EL LITORAL El Instituto Nacional de Patrimonio Cultural Direcci\u00f3n Regional 5 ante las declaraciones de ciertos ciudadanos que est\u00e1n escribiendo al portal Facebook de la regional 5 (Patrimonio Vivo) sobre una denuncia que el INPC no ha actuado en respuesta a la salvaguarda del patrimonio cultural de la pen\u00ednsula en cuanto al hallazgo arqueol\u00f3gico [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pachamamitaecu.org\/es_es\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/\" \/>\n<meta property=\"og:site_name\" content=\"PachaMamita Ecuador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pachamamitaecu\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-25T04:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s320\/296583_2237679232207_1554784837_2444431_4248601_n.jpg\" \/>\n<meta name=\"author\" content=\"PachaMamita EC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PachaMamita EC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/\"},\"author\":{\"name\":\"PachaMamita EC\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\"},\"headline\":\"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio\",\"datePublished\":\"2011-08-25T04:09:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/\"},\"wordCount\":982,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-5sFvNVMFQYk\\\/TlXKw4JzCwI\\\/AAAAAAAABSw\\\/zD9GnkqGGMQ\\\/s320\\\/296583_2237679232207_1554784837_2444431_4248601_n.jpg\",\"articleSection\":[\"noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/\",\"name\":\"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio - PachaMamita Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-5sFvNVMFQYk\\\/TlXKw4JzCwI\\\/AAAAAAAABSw\\\/zD9GnkqGGMQ\\\/s320\\\/296583_2237679232207_1554784837_2444431_4248601_n.jpg\",\"datePublished\":\"2011-08-25T04:09:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#primaryimage\",\"url\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-5sFvNVMFQYk\\\/TlXKw4JzCwI\\\/AAAAAAAABSw\\\/zD9GnkqGGMQ\\\/s320\\\/296583_2237679232207_1554784837_2444431_4248601_n.jpg\",\"contentUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-5sFvNVMFQYk\\\/TlXKw4JzCwI\\\/AAAAAAAABSw\\\/zD9GnkqGGMQ\\\/s320\\\/296583_2237679232207_1554784837_2444431_4248601_n.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/en\\\/2011\\\/08\\\/25\\\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"name\":\"PachaMamita Ecuador\",\"description\":\"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\",\"name\":\"PachaMamita Ecuador\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"width\":512,\"height\":512,\"caption\":\"PachaMamita Ecuador\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pachamamitaecu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\",\"name\":\"PachaMamita EC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/litespeed\\\/avatar\\\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/litespeed\\\/avatar\\\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/litespeed\\\/avatar\\\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103\",\"caption\":\"PachaMamita EC\"},\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/author\\\/pachamamita-ec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio - PachaMamita Ecuador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pachamamitaecu.org\/es_es\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/","og_locale":"es_ES","og_type":"article","og_title":"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio","og_description":"FOTO: EL LITORAL El Instituto Nacional de Patrimonio Cultural Direcci\u00f3n Regional 5 ante las declaraciones de ciertos ciudadanos que est\u00e1n escribiendo al portal Facebook de la regional 5 (Patrimonio Vivo) sobre una denuncia que el INPC no ha actuado en respuesta a la salvaguarda del patrimonio cultural de la pen\u00ednsula en cuanto al hallazgo arqueol\u00f3gico [...]","og_url":"https:\/\/pachamamitaecu.org\/es_es\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/","og_site_name":"PachaMamita Ecuador","article_publisher":"https:\/\/www.facebook.com\/pachamamitaecu","article_published_time":"2011-08-25T04:09:00+00:00","og_image":[{"url":"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s320\/296583_2237679232207_1554784837_2444431_4248601_n.jpg","type":"","width":"","height":""}],"author":"PachaMamita EC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PachaMamita EC","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#article","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/"},"author":{"name":"PachaMamita EC","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593"},"headline":"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio","datePublished":"2011-08-25T04:09:00+00:00","mainEntityOfPage":{"@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/"},"wordCount":982,"commentCount":0,"publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"image":{"@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s320\/296583_2237679232207_1554784837_2444431_4248601_n.jpg","articleSection":["noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/","url":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/","name":"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio - PachaMamita Ecuador","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#primaryimage"},"image":{"@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s320\/296583_2237679232207_1554784837_2444431_4248601_n.jpg","datePublished":"2011-08-25T04:09:00+00:00","breadcrumb":{"@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#primaryimage","url":"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s320\/296583_2237679232207_1554784837_2444431_4248601_n.jpg","contentUrl":"http:\/\/2.bp.blogspot.com\/-5sFvNVMFQYk\/TlXKw4JzCwI\/AAAAAAAABSw\/zD9GnkqGGMQ\/s320\/296583_2237679232207_1554784837_2444431_4248601_n.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/pachamamitaecu.org\/en\/2011\/08\/25\/inpc-announces-actions-for-property-destruction-in-la-libertad-during-municipal-work\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pachamamitaecu.org\/es_es\/"},{"@type":"ListItem","position":2,"name":"INPC anuncia acciones por destrucci\u00f3n patrimonial en La Libertad durante labores del Municipio"}]},{"@type":"WebSite","@id":"https:\/\/pachamamitaecu.org\/es_es\/#website","url":"https:\/\/pachamamitaecu.org\/es_es\/","name":"PachaMamita Ecuador","description":"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.","publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pachamamitaecu.org\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization","name":"PachaMamita Ecuador","url":"https:\/\/pachamamitaecu.org\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","width":512,"height":512,"caption":"PachaMamita Ecuador"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pachamamitaecu"]},{"@type":"Person","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593","name":"PachaMamita EC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/wp-content\/litespeed\/avatar\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103","url":"https:\/\/pachamamitaecu.org\/wp-content\/litespeed\/avatar\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/litespeed\/avatar\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103","caption":"PachaMamita EC"},"url":"https:\/\/pachamamitaecu.org\/es_es\/author\/pachamamita-ec\/"}]}},"_links":{"self":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/comments?post=1197"}],"version-history":[{"count":0,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1197\/revisions"}],"wp:attachment":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/media?parent=1197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories?post=1197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/tags?post=1197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}