{"id":1560,"date":"2009-12-05T04:49:00","date_gmt":"2009-12-05T04:49:00","guid":{"rendered":"http:\/\/pachamamitaecu-org-720647.hostingersite.com\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/"},"modified":"2009-12-05T04:49:00","modified_gmt":"2009-12-05T04:49:00","slug":"sos-salvemos-a-la-ola-de-san-mateo","status":"publish","type":"post","link":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/","title":{"rendered":"SOS Salvemos a la ola de San Mateo"},"content":{"rendered":"<p><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\"><span style=\"color: red;\">LA OLA MAS LARGA DEL ECUADOR ESTA EN PELIGRO<\/span><\/span><\/span><br \/><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">La ola de San Mateo; la mas larga del Ecuador, ya que en un buen dia puede extenderse un kilometro o mas, y es una de las favoritas por muchos surfistas locales y extranjeros; corre el serio peligro de desaparecer con la planificada construccion de un muelle para la pesca.<\/span><\/span><\/span><\/p>\n<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg\" style=\"clear: left; float: left; margin-bottom: 1em; margin-right: 1em;\"><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\"><img decoding=\"async\" border=\"0\" height=\"240\" data-src=\"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg\" width=\"320\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 320px; --smush-placeholder-aspect-ratio: 320\/240;\" \/><\/span><\/span><\/span><\/a><\/div>\n<p><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">Este proyecto que es respaldado por el Estado, arranco desde hace unos dos a\u00f1os y ha generado mucha controversia por el creciente numero de personas que se oponen a el , tanto de la comunidad como visitantes de su famosa izquierda. Este es un criterio que al parecer no ha sido observado por el informe de impacto ambiental, puesto que en ese tipo de informes es de alta prioridad las consideraciones del factor poblacion.<\/span><\/span><\/span><br \/><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">Fabrizio Vera, Secretario del Comite \u00abSalvemos la ola de San Mateo\u00bb, nos comento que el proyecto inicialmente fue planeado para ser ubicado en la punta , con la desaparicion por completo de la tan famosa ola &nbsp;Tras muchas diligencias hasta el momento la propuesta fue cambiada hacia el margen derecho de la salida del rio; sin embargo en esa ubicacion la ola sigue en peligro pues se partiria en dos.<\/span><\/span><\/span><br \/><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">La tercera propuesta y a la que solicitamos su adhesion al grupo SOS (Salvemos la Ola de San Mateo); es la de construir el muelle pero hacia el final del pueblo; en donde no seria afectada la ola.<\/span><\/span><\/span><br \/><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">Fabrizio nos comento que hasta el momento la licencia que debe otorgar el Ministerio de Ambiente no ha sido aprobada; por lo que esta campa\u00f1a de salvar este recurso deportivo y turistico esta en su momento de ser apoyada; y nos insistio que la propuesta no es en contra de la construccion del muelle , sino en el cambio de su ubicacion.<\/span><\/span><\/span><br \/><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\"><br \/><\/span><\/span> <\/span><br \/><span style=\"color: purple;\"><span style=\"font-size: x-large;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">Quienes esten interesados en unirse al grupo de apoyo pueden hacerlo a este link&nbsp;<\/span><\/span><\/span><span style=\"color: purple;\"><a href=\"http:\/\/www.facebook.com\/group.php?v=info&amp;ref=ss&amp;gid=133691774009\">http:\/\/www.facebook.com\/group.php?v=info&amp;ref=ss&amp;gid=133691774009<\/a><\/span><br \/><span style=\"color: purple;\"><br \/><\/span><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_1560\" class=\"pvc_stats total_only  \" data-element-id=\"1560\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/pachamamitaecu.org\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>LA OLA MAS LARGA DEL ECUADOR ESTA EN PELIGROLa ola de San Mateo; la mas larga del Ecuador, ya que en un buen dia puede extenderse un kilometro o mas, y es una de las favoritas por muchos surfistas locales y extranjeros; corre el serio peligro de desaparecer con la planificada construccion de un muelle [&#8230;]\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175,159,577],"tags":[],"class_list":["post-1560","post","type-post","status-publish","format-standard","hentry","category-conservacion","category-consumo-responsable","category-informacion"],"a3_pvc":{"activated":true,"total_views":47,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SOS Salvemos a la ola de San Mateo - PachaMamita Ecuador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOS Salvemos a la ola de San Mateo\" \/>\n<meta property=\"og:description\" content=\"LA OLA MAS LARGA DEL ECUADOR ESTA EN PELIGROLa ola de San Mateo; la mas larga del Ecuador, ya que en un buen dia puede extenderse un kilometro o mas, y es una de las favoritas por muchos surfistas locales y extranjeros; corre el serio peligro de desaparecer con la planificada construccion de un muelle [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/\" \/>\n<meta property=\"og:site_name\" content=\"PachaMamita Ecuador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pachamamitaecu\" \/>\n<meta property=\"article:published_time\" content=\"2009-12-05T04:49:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg\" \/>\n<meta name=\"author\" content=\"PachaMamita EC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PachaMamita EC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/\"},\"author\":{\"name\":\"PachaMamita EC\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\"},\"headline\":\"SOS Salvemos a la ola de San Mateo\",\"datePublished\":\"2009-12-05T04:49:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/\"},\"wordCount\":339,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.surfosmagazine.com\\\/Imagenes\\\/Ecologia-secundaria45.jpg\",\"articleSection\":[\"CONSERVACI\u00d3N\",\"CONSUMO RESPONSABLE\",\"informacion\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/\",\"name\":\"SOS Salvemos a la ola de San Mateo - PachaMamita Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.surfosmagazine.com\\\/Imagenes\\\/Ecologia-secundaria45.jpg\",\"datePublished\":\"2009-12-05T04:49:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.surfosmagazine.com\\\/Imagenes\\\/Ecologia-secundaria45.jpg\",\"contentUrl\":\"http:\\\/\\\/www.surfosmagazine.com\\\/Imagenes\\\/Ecologia-secundaria45.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2009\\\/12\\\/05\\\/sos-salvemos-a-la-ola-de-san-mateo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOS Salvemos a la ola de San Mateo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"name\":\"PachaMamita Ecuador\",\"description\":\"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\",\"name\":\"PachaMamita Ecuador\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"width\":512,\"height\":512,\"caption\":\"PachaMamita Ecuador\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pachamamitaecu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\",\"name\":\"PachaMamita EC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"PachaMamita EC\"},\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/author\\\/pachamamita-ec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SOS Salvemos a la ola de San Mateo - PachaMamita Ecuador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/","og_locale":"es_ES","og_type":"article","og_title":"SOS Salvemos a la ola de San Mateo","og_description":"LA OLA MAS LARGA DEL ECUADOR ESTA EN PELIGROLa ola de San Mateo; la mas larga del Ecuador, ya que en un buen dia puede extenderse un kilometro o mas, y es una de las favoritas por muchos surfistas locales y extranjeros; corre el serio peligro de desaparecer con la planificada construccion de un muelle [...]","og_url":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/","og_site_name":"PachaMamita Ecuador","article_publisher":"https:\/\/www.facebook.com\/pachamamitaecu","article_published_time":"2009-12-05T04:49:00+00:00","og_image":[{"url":"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg","type":"","width":"","height":""}],"author":"PachaMamita EC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PachaMamita EC","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#article","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/"},"author":{"name":"PachaMamita EC","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593"},"headline":"SOS Salvemos a la ola de San Mateo","datePublished":"2009-12-05T04:49:00+00:00","mainEntityOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/"},"wordCount":339,"commentCount":1,"publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg","articleSection":["CONSERVACI\u00d3N","CONSUMO RESPONSABLE","informacion"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/","url":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/","name":"SOS Salvemos a la ola de San Mateo - PachaMamita Ecuador","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#primaryimage"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#primaryimage"},"thumbnailUrl":"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg","datePublished":"2009-12-05T04:49:00+00:00","breadcrumb":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#primaryimage","url":"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg","contentUrl":"http:\/\/www.surfosmagazine.com\/Imagenes\/Ecologia-secundaria45.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/pachamamitaecu.org\/es_es\/2009\/12\/05\/sos-salvemos-a-la-ola-de-san-mateo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pachamamitaecu.org\/es_es\/"},{"@type":"ListItem","position":2,"name":"SOS Salvemos a la ola de San Mateo"}]},{"@type":"WebSite","@id":"https:\/\/pachamamitaecu.org\/es_es\/#website","url":"https:\/\/pachamamitaecu.org\/es_es\/","name":"PachaMamita Ecuador","description":"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.","publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pachamamitaecu.org\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization","name":"PachaMamita Ecuador","url":"https:\/\/pachamamitaecu.org\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","width":512,"height":512,"caption":"PachaMamita Ecuador"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pachamamitaecu"]},{"@type":"Person","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593","name":"PachaMamita EC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"PachaMamita EC"},"url":"https:\/\/pachamamitaecu.org\/es_es\/author\/pachamamita-ec\/"}]}},"_links":{"self":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/comments?post=1560"}],"version-history":[{"count":0,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/1560\/revisions"}],"wp:attachment":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/media?parent=1560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories?post=1560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/tags?post=1560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}