{"id":678,"date":"2013-07-27T18:07:00","date_gmt":"2013-07-27T18:07:00","guid":{"rendered":"http:\/\/pachamamitaecu-org-720647.hostingersite.com\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/"},"modified":"2023-03-02T06:22:12","modified_gmt":"2023-03-02T06:22:12","slug":"cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador","status":"publish","type":"post","link":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/","title":{"rendered":"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador."},"content":{"rendered":"<table cellpadding=\"0\" cellspacing=\"0\" style=\"float: left; margin-right: 1em; text-align: left;\">\n<tbody>\n<tr>\n<td style=\"text-align: center;\"><a href=\"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s1600\/19081_10152439232010594_73953147_n.jpg\" style=\"clear: left; margin-bottom: 1em; margin-left: auto; margin-right: auto;\"><img decoding=\"async\" border=\"0\" height=\"226\" data-src=\"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s320\/19081_10152439232010594_73953147_n.jpg\" width=\"320\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 320px; --smush-placeholder-aspect-ratio: 320\/226;\" \/><\/a><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\"><span style=\"font-size: small;\">Dibujo realizado por un ni\u00f1o<br \/>&nbsp;de la amazon\u00eda ecuatoriana<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">Hacia finales del a\u00f1o pasado, el ex-ministro de Recursos No Renovables, Wilson P\u00e1stor, anunciaba en rueda de prensa que entre las empresas interesadas en participar en la actual ronda de licitaciones de los bloques del sur de la amazon\u00eda ecuatoriana, se cuenta a Petrominerales, Pacific Rubiales y Conacol; Petrosud, Repsol, la canadiense Talisman Energy, tres empresas de Estados Unidos (no especific\u00f3 sus nombres), adem\u00e1s de las estatales Petrovietnam y Turkish National Oil and Gas.<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">El discurso oficial es que las empresas vendr\u00e1n a nuestro pa\u00eds con \u00abtecnolog\u00eda de punta\u00bb &nbsp;para operar en una de las zonas m\u00e1s sensibles y de mayor biodiversidad del planeta.<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Sin embargo, al realizar un breve resumen de las informaciones encontradas en la internet respecto a las operaciones de estas compa\u00f1\u00edas en Am\u00e9rica Latina y en otras partes del planeta, es f\u00e1cil darse cuenta que los discursos oficiales (estatales y empresariales) distan de lo que ocurre realmente en las zonas donde operan.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<p><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\">Todas las referencias se pueden encontrar en la parte inferior de este an\u00e1lisis:<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><b style=\"font-weight: bold;\"><u>Petrominerales<\/u><\/b> (Empresa Canadiense, cuarto mayor explotador de crudo en Colombia). En el 2011 debieron suspender su producci\u00f3n por m\u00e1s de una semana debido a los fuertes reclamos de las comunidades en el municipio Barranca de Upia, quienes la acusaron de \u00abviolar los derechos de los obreros y contaminar el medio ambiente\u00bb. (1)<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\"><b style=\"font-weight: bold;\"><u>Pacific Rubiales<\/u><\/b><b>, <\/b>empresa canadiense formada por venezolanos, se la relaciona en Colombia a p\u00e9rdida del territorio de pueblos ind\u00edgenas, permeabilizaci\u00f3n cultural y fragmentaci\u00f3n, p\u00e9rdida de valores, pobreza, miseria y violencia generalizada. En el 2011, estall\u00f3 una huelga pro parte de los trabajadores que ped\u00edan  estabilidad laboral, salario digno, libertad de asociaci\u00f3n, seguridad industrial, entre otros. Al conflicto, el gobierno colombiano se vi\u00f3 obligado a darle \u00abtrato de guerra\u00bb  (3) por el despido de m\u00e1s de 1,500 trabajadores por parte de la empresa. El<a href=\"http:\/\/www.palabrasalmargen.com\/index.php\/articulos\/item\/cronologia-de-un-conflicto-el-caso-de-los-trabajadores-petroleros-de-puerto-gaitan-meta\"> <span style=\"color: #990000;\">siguiente enlace<\/span><\/a>&nbsp;(4) proporciona una amplia bibliograf\u00eda sobre los conflictos de la Pacific Rubiales en Colombia, donde opera los campos de mayor producci\u00f3n de ese pa\u00eds.&nbsp;<\/div>\n<p><\/span><\/p>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Publicidad enga\u00f1osa, consultas previas ama\u00f1adas, falta de compromiso social, abuso de autoridad &nbsp;son algunas otras de las acusaciones que &nbsp;se le hacen a esta empresa interesada en participar de la explotaci\u00f3n petrolera de los bloques sur en Ecuador. (5)<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><u style=\"font-weight: bold;\">Canacol,<\/u>&nbsp;enfoca sus operaciones en Ecuador y Colombia.<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><b><u>Petrosud<\/u><\/b>, &nbsp;ha operado campos marginales en Ecuador.<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><u style=\"font-family: Georgia, 'Times New Roman', serif; font-weight: bold;\">Talisman Energy,<\/u><span style=\"font-family: Georgia, 'Times New Roman', serif;\">&nbsp;<\/span><span style=\"background-color: white; font-family: Georgia, 'Times New Roman', serif; line-height: 18px;\">empresa canadiense de exploraci\u00f3n, desarrollo, producci\u00f3n y comercializaci\u00f3n de petr\u00f3leo crudo y gas natural.&nbsp;<\/span><span style=\"background-color: white; font-family: Georgia, 'Times New Roman', serif; line-height: 18px;\">Talism\u00e1n fue acusada de genocidio por proporcionar apoyo al gobierno de Sud\u00e1n y financiar a grupos paramilitares durante la guerra civil que caus\u00f3 la muerte de unas dos millones de personas.&nbsp;<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"background-color: white; font-family: Georgia, Times New Roman, serif; line-height: 18px;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"background-color: white;\"><span style=\"font-family: Georgia, Times New Roman, serif; line-height: 18px;\">Aunque la empresa manifestara que \u00abhab\u00edan aprendido la lecci\u00f3n de Sud\u00e1n\u00bb en el 2009 ingres\u00f3 a la selva peruana sin ning\u00fan tipo de consulta previa o concenso. (6)<\/span><\/span><\/div>\n<p><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, 'Times New Roman', serif; line-height: 18px;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><span style=\"background-color: white; line-height: 19px;\">Tambi\u00e9n en el 2011, los achuar (de Per\u00fa) acusaron a Talism\u00e1n (en la misma Canad\u00e1) de contaminar su medio ambiente con desechos t\u00f3xicos e incitar violencia y divisiones entre los ind\u00edgenas para mantener sus actividades petrol\u00edferas en su territorio tradicional, a la vez que exigieron la salida de su territorio &nbsp;(7). &nbsp;Finalmente en el 2012, Talisman Energy anunci\u00f3 su retirada de Per\u00fa. Hoy es una de las empresas que aspiran explotar petr\u00f3leo en Ecuador.<\/span><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><span style=\"background-color: white; line-height: 19px;\"><br \/><\/span><\/span><\/div>\n<div style=\"text-align: justify;\"><b style=\"font-family: Georgia, 'Times New Roman', serif; text-decoration: underline;\">Repsol,<\/b><span style=\"font-family: Georgia, 'Times New Roman', serif;\">&nbsp;sin duda alguna Repsol YPF , una de las gigantes del negocio, es tambi\u00e9n una de las que m\u00e1s conflictos mantiene en los territorios donde opera debido principalmente a temas ambientales y sociales.<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">La web&nbsp;<span style=\"color: #990000;\"><a href=\"http:\/\/repsolmata.ourproject.org\/\"><span style=\"color: #990000;\">RepsolMata<\/span><\/a>&nbsp;<\/span>re\u00fane una gran cantidad (siempre actualizada) de los incidentes de esta empresa alrededor del mundo.<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">El m\u00e1s reciente de los casos da cuenta que Repsol habr\u00eda ocultado una fuga de 6.000 toneladas de gasolina en Tarragona (Espa\u00f1a) (8), &nbsp;que junto al derrame ocurrido en febrero del 2013 en Callao, Per\u00fa donde se verti\u00f3 una gran cantidad de crudo que cubri\u00f3 cerca de dos kil\u00f3metros de largo y m\u00e1s de 50 mts. de ancho.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Ambos casos ponen en duda las \u00abtecnolog\u00edas de punta\u00bb con las que se promocionan sus operaciones y con las cuales tambi\u00e9n es una de las empresas que pretenden operar en una de las zonas m\u00e1s sensibles y de mayor biodiversidad del planeta, en la amazon\u00eda ecuatoriana.<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\"><b><u>Referencias:<\/u><\/b><\/span><\/div>\n<\/div>\n<div>\n<div><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">1. http:\/\/www.avn.info.ve\/contenido\/obreros-paralizan-petrolera-canadiense-colombia-para-exigi<\/span><span style=\"font-family: Georgia, 'Times New Roman', serif;\">r-mejoras-laborales.<\/span><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/div>\n<div><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, 'Times New Roman', serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">3. http:\/\/www.pasc.ca\/es\/article\/conflicto-laboral-con-la-canadiense-pacific-rubiales-recibe-trato-de-guerra<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">4.&nbsp;http:\/\/www.palabrasalmargen.com\/index.php\/articulos\/item\/cronologia-de-un-conflicto-el-caso-de-los-trabajadores-petroleros-de-puerto-gaitan-meta<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">5.&nbsp;http:\/\/www.elnuevodia.com.co\/nuevodia\/especiales\/ecologica\/159167-los-pecados-de-pacific-rubiales<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">6.&nbsp;<\/span><span style=\"background-color: white; font-family: Arial, 'Segoe UI', Helvetica, sans-serif; line-height: 18px;\">http:\/\/grancomboclub.com\/2009\/04\/la-segunda-gran-protesta-amazonica.html<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">7. &nbsp;http:\/\/www.ahoracanada.com\/negocios\/indigenas-achuar-exigen-a-talisman-que-salga-de-su-territorio.html<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">8.&nbsp;http:\/\/repsolmata.ourproject.org\/spip.php?article249<\/span><\/div>\n<\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_678\" class=\"pvc_stats total_only  \" data-element-id=\"678\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/pachamamitaecu.org\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dibujo realizado por un ni\u00f1o&nbsp;de la amazon\u00eda ecuatoriana Hacia finales del a\u00f1o pasado, el ex-ministro de Recursos No Renovables, Wilson P\u00e1stor, anunciaba en rueda de prensa que entre las empresas interesadas en participar en la actual ronda de licitaciones de los bloques del sur de la amazon\u00eda ecuatoriana, se cuenta a Petrominerales, Pacific Rubiales y [&#8230;]\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[144,142,408,188,185,187,193,191],"tags":[],"class_list":["post-678","post","type-post","status-publish","format-standard","hentry","category-cofan","category-cofanes","category-derrame-petroleo","category-madera-petroleo-y-resistencia","category-pueblos-indigenas","category-ronda-petrolera","category-sarayacu","category-sarayaku"],"a3_pvc":{"activated":true,"total_views":26,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador. - PachaMamita Ecuador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador.\" \/>\n<meta property=\"og:description\" content=\"Dibujo realizado por un ni\u00f1o&nbsp;de la amazon\u00eda ecuatoriana Hacia finales del a\u00f1o pasado, el ex-ministro de Recursos No Renovables, Wilson P\u00e1stor, anunciaba en rueda de prensa que entre las empresas interesadas en participar en la actual ronda de licitaciones de los bloques del sur de la amazon\u00eda ecuatoriana, se cuenta a Petrominerales, Pacific Rubiales y [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/\" \/>\n<meta property=\"og:site_name\" content=\"PachaMamita Ecuador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pachamamitaecu\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-27T18:07:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T06:22:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s320\/19081_10152439232010594_73953147_n.jpg\" \/>\n<meta name=\"author\" content=\"PachaMamita EC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PachaMamita EC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/\"},\"author\":{\"name\":\"PachaMamita EC\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\"},\"headline\":\"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador.\",\"datePublished\":\"2013-07-27T18:07:00+00:00\",\"dateModified\":\"2023-03-02T06:22:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/\"},\"wordCount\":828,\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-JiaFPQgh2Zo\\\/USLiGT9SqzI\\\/AAAAAAAADcA\\\/X-UVX_mj9iw\\\/s320\\\/19081_10152439232010594_73953147_n.jpg\",\"articleSection\":[\"cofan\",\"cofanes\",\"derrame petroleo\",\"MADERA PETROLEO Y RESISTENCIA\",\"pueblos indigenas\",\"ronda petrolera\",\"sarayacu\",\"sarayaku\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/\",\"name\":\"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador. - PachaMamita Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-JiaFPQgh2Zo\\\/USLiGT9SqzI\\\/AAAAAAAADcA\\\/X-UVX_mj9iw\\\/s320\\\/19081_10152439232010594_73953147_n.jpg\",\"datePublished\":\"2013-07-27T18:07:00+00:00\",\"dateModified\":\"2023-03-02T06:22:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/#primaryimage\",\"url\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-JiaFPQgh2Zo\\\/USLiGT9SqzI\\\/AAAAAAAADcA\\\/X-UVX_mj9iw\\\/s320\\\/19081_10152439232010594_73953147_n.jpg\",\"contentUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-JiaFPQgh2Zo\\\/USLiGT9SqzI\\\/AAAAAAAADcA\\\/X-UVX_mj9iw\\\/s320\\\/19081_10152439232010594_73953147_n.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2013\\\/07\\\/27\\\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"name\":\"PachaMamita Ecuador\",\"description\":\"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\",\"name\":\"PachaMamita Ecuador\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"width\":512,\"height\":512,\"caption\":\"PachaMamita Ecuador\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pachamamitaecu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\",\"name\":\"PachaMamita EC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"PachaMamita EC\"},\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/author\\\/pachamamita-ec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador. - PachaMamita Ecuador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/","og_locale":"es_ES","og_type":"article","og_title":"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador.","og_description":"Dibujo realizado por un ni\u00f1o&nbsp;de la amazon\u00eda ecuatoriana Hacia finales del a\u00f1o pasado, el ex-ministro de Recursos No Renovables, Wilson P\u00e1stor, anunciaba en rueda de prensa que entre las empresas interesadas en participar en la actual ronda de licitaciones de los bloques del sur de la amazon\u00eda ecuatoriana, se cuenta a Petrominerales, Pacific Rubiales y [...]","og_url":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/","og_site_name":"PachaMamita Ecuador","article_publisher":"https:\/\/www.facebook.com\/pachamamitaecu","article_published_time":"2013-07-27T18:07:00+00:00","article_modified_time":"2023-03-02T06:22:12+00:00","og_image":[{"url":"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s320\/19081_10152439232010594_73953147_n.jpg","type":"","width":"","height":""}],"author":"PachaMamita EC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PachaMamita EC","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/#article","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/"},"author":{"name":"PachaMamita EC","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593"},"headline":"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador.","datePublished":"2013-07-27T18:07:00+00:00","dateModified":"2023-03-02T06:22:12+00:00","mainEntityOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/"},"wordCount":828,"publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s320\/19081_10152439232010594_73953147_n.jpg","articleSection":["cofan","cofanes","derrame petroleo","MADERA PETROLEO Y RESISTENCIA","pueblos indigenas","ronda petrolera","sarayacu","sarayaku"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/","url":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/","name":"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador. - PachaMamita Ecuador","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/#primaryimage"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s320\/19081_10152439232010594_73953147_n.jpg","datePublished":"2013-07-27T18:07:00+00:00","dateModified":"2023-03-02T06:22:12+00:00","breadcrumb":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/#primaryimage","url":"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s320\/19081_10152439232010594_73953147_n.jpg","contentUrl":"http:\/\/2.bp.blogspot.com\/-JiaFPQgh2Zo\/USLiGT9SqzI\/AAAAAAAADcA\/X-UVX_mj9iw\/s320\/19081_10152439232010594_73953147_n.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/pachamamitaecu.org\/es_es\/2013\/07\/27\/cuales-son-las-empresas-interesadas-en-la-actual-ronda-de-licitaciones-en-ecuador\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pachamamitaecu.org\/es_es\/"},{"@type":"ListItem","position":2,"name":"Cu\u00e1les son las empresas interesadas en la actual ronda de licitaciones en Ecuador."}]},{"@type":"WebSite","@id":"https:\/\/pachamamitaecu.org\/es_es\/#website","url":"https:\/\/pachamamitaecu.org\/es_es\/","name":"PachaMamita Ecuador","description":"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.","publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pachamamitaecu.org\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization","name":"PachaMamita Ecuador","url":"https:\/\/pachamamitaecu.org\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","width":512,"height":512,"caption":"PachaMamita Ecuador"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pachamamitaecu"]},{"@type":"Person","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593","name":"PachaMamita EC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"PachaMamita EC"},"url":"https:\/\/pachamamitaecu.org\/es_es\/author\/pachamamita-ec\/"}]}},"_links":{"self":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/comments?post=678"}],"version-history":[{"count":0,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/678\/revisions"}],"wp:attachment":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/media?parent=678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories?post=678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/tags?post=678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}