{"id":987,"date":"2012-04-18T07:57:00","date_gmt":"2012-04-18T07:57:00","guid":{"rendered":"http:\/\/pachamamitaecu-org-720647.hostingersite.com\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/"},"modified":"2023-03-01T15:27:25","modified_gmt":"2023-03-01T15:27:25","slug":"corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil","status":"publish","type":"post","link":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/","title":{"rendered":"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil"},"content":{"rendered":"<div style=\"clear: both; text-align: center;\"><a href=\"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s1600\/logo.jpg\" style=\"margin-left: 1em; margin-right: 1em;\"><img decoding=\"async\" border=\"0\" height=\"141\" data-src=\"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s400\/logo.jpg\" width=\"400\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 400px; --smush-placeholder-aspect-ratio: 400\/141;\" \/><\/a><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">La Corte Interamericana de Derechos Humanos llegar\u00e1 en los pr\u00f3ximos d\u00edas a Ecuador. Durante su estad\u00eda visitar\u00e1 el pueblo originario kichwa de Sarayaku (Prov. de Pastaza) a partir del d\u00eda s\u00e1bado 21 de abril  y luego celebrar\u00e1 del 23 al 27 de este mismo mes, en Guayaquil, su 45\u00ba Per\u00edodo Extraordinario de Sesiones .<\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">La visita de la Corte a Sarayaku  es para realizar una inspecci\u00f3n que se enmarca dentro de la demanda que este pueblo tiene interpuesta en el Sistema Interamericano de Derechos Humanos, luego que el estado estado ecuatoriano concesion\u00f3 el bloque 23 a favor de la empresa argentina CGC, sin &nbsp;ning\u00fan proceso de informaci\u00f3n, consulta o pedido de consentimiento al pueblo de Sarayaku para la realizaci\u00f3n de actividades petroleras en su territorio; y, donde este organismo est\u00e1 pr\u00f3ximo a dictar sentencia. Seg\u00fan Mario Santi, vocero de los kichwas de Sarayaku, los miembros de la Corte llegar\u00e1n primero a Shell -Mera el d\u00eda viernes donde pernoctaran, para ingresar v\u00eda a\u00e9rea el d\u00eda s\u00e1bado a la comunidad.<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Luego se tiene previsto el viaje a la ciudad de Guayaquil de los miembros de la Corte y de una comisi\u00f3n de cerca de 20 personas representantes del pueblo de Sarayaku quienes participar\u00e1n de diversas actividades relativas en el puerto principal.<\/span><\/div>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Durante la pr\u00f3xima semana, la Corte celebrar\u00e1 tres audiencias p\u00fablicas y el martes 24 se llevar\u00e1 a cabo el seminario \u00abJurisprudencia de la Corte Interamericana de Derechos Humanos\u00bb con los temas:<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<ul>\n<li style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Derechos de los Pueblos Ind\u00edgenas en la Jurisprudencia de la Corte Interamericana de Derechos Humanos. &nbsp;<i>Jorge Calder\u00f3n, Abogado Corte Interamericana de Derechos Humanos.<\/i><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Derecho a la Integridad Personal. <i>Romina Sijniensky, Abogada Corte Interamericana de Derechos Humanos.<\/i><\/span><\/li>\n<li style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Control de la Convencionalidad.&nbsp;Olger Gonz\u00e1lez, <i>Abogado Corte Interamericana de Derechos Humanos.<\/i><\/span><\/li>\n<\/ul>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Seg\u00fan Santi, estos 3 temas est\u00e1n relacionados a la causa presentada por su pueblo por derechos humanos contra el estado ecuatoriano.<\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/span><\/p>\n<div>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/div>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><\/p>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Las sesiones de la Corte tratar\u00e1n casos pendientes de otros pa\u00edses de latinoam\u00e9rica. El caso Sarayaku no ser\u00e1 tratado en las audiencias que la Corte realizar\u00e1 en Ecuador seg\u00fan se anuncia en la web de la CIDH; en cambio se analizar\u00e1n los siguientes:&nbsp;<\/span><\/div>\n<ul>\n<li><span style=\"font-family: Georgia, Times New Roman, serif;\"><a href=\"http:\/\/www.corteidh.or.cr\/guayaquil\/mozote.pdf\" style=\"text-align: justify;\">Caso Masacres de El Mozote vs. El Salvador<\/a><span style=\"text-align: justify;\"> .&nbsp;Lunes 23.&nbsp;<\/span><\/span><\/li>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\">Caso Forner\u00f3n e Hija Vs. Argentina. Sentencia sobre Fondo, Reparaciones y Costas. Martes 24.&nbsp; <\/span><\/p>\n<li><span style=\"font-family: Georgia, Times New Roman, serif;\"><a href=\"http:\/\/www.corteidh.or.cr\/guayaquil\/gudiel.pdf\">Caso Gudiel \u00c1lvarez y otros (Diario El Militar) vs. Guatemala<\/a> . Mi\u00e9rcoles 25.&nbsp;<\/span><\/li>\n<li><span style=\"font-family: Georgia, Times New Roman, serif;\"><a href=\"http:\/\/www.corteidh.or.cr\/guayaquil\/garcia.pdf\">Caso Garc\u00eda y familiares vs. Guatemala.<\/a> &nbsp;Jueves 26&nbsp;<\/span><\/li>\n<li><span style=\"font-family: Georgia, Times New Roman, serif;\">Caso Pacheco Teruel y otros Vs. Honduras. Sentencia sobre Fondo, Reparaciones y Costas.<\/span><\/li>\n<p><span style=\"font-family: Georgia, Times New Roman, serif;\"><\/p>\n<ul style=\"text-align: justify;\"><\/ul>\n<div style=\"text-align: justify;\">Todas las audiencias se llevar\u00e1n a cabo desde las &nbsp;9:00 hrs. en el&nbsp;<span style=\"background-color: white; color: #706f6f; line-height: 18px; text-align: justify;\">&nbsp;<\/span>Centro de Convenciones de Guayaquil Sim\u00f3n Bolivar, Sala \u00abAlfredo Baquerizo Moreno\u00bb; mientras que el seminario ser\u00e1 en la Universidad Cat\u00f3lica Santiago de Guayaquil. Facultad de Derecho. Sala Vicente Rocafuerte, de 16:30 a 18:30 hrs. Para cualquiera de los dos eventos es necesario solicitar invitaci\u00f3n <a href=\"http:\/\/www.corteidh.or.cr\/Guayaquil\/inscripcion.html\">desde aqui.<\/a><\/div>\n<p><\/span><\/ul>\n<div style=\"text-align: justify;\"><span style=\"font-family: Georgia, Times New Roman, serif;\">Diversas actividades de apoyo al pueblo kichwa de Sarayaku se realizar\u00e1n durante esos d\u00edas, entre ellos conversatorios , visitas de medios y una MARAT\u00d3N DE CINE AMAZ\u00d3NICO que se llevar\u00e1 en el MAAC Cine durante todo el d\u00eda domingo 28 con la presentaci\u00f3n de pel\u00edculas, documentales y cortos relativos a la tem\u00e1tica.<\/span><br \/><span style=\"font-family: Georgia, Times New Roman, serif;\"><br \/><\/span><span style=\"font-family: Georgia, Times New Roman, serif;\">Ecuador forma parte del&nbsp;Sistema Interamericano de Protecci\u00f3n de los Derechos Humanos y las resoluciones de la Corte (por ejemplo en el caso Sarayaku) son de obligatorio cumplimiento.&nbsp;<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_987\" class=\"pvc_stats total_only  \" data-element-id=\"987\" style=\"\"><i class=\"pvc-stats-icon medium\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" data-src=\"https:\/\/pachamamitaecu.org\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Corte Interamericana de Derechos Humanos llegar\u00e1 en los pr\u00f3ximos d\u00edas a Ecuador. Durante su estad\u00eda visitar\u00e1 el pueblo originario kichwa de Sarayaku (Prov. de Pastaza) a partir del d\u00eda s\u00e1bado 21 de abril y luego celebrar\u00e1 del 23 al 27 de este mismo mes, en Guayaquil, su 45\u00ba Per\u00edodo Extraordinario de Sesiones . La [&#8230;]\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[159,264,193,191],"tags":[],"class_list":["post-987","post","type-post","status-publish","format-standard","hentry","category-consumo-responsable","category-noticias","category-sarayacu","category-sarayaku"],"a3_pvc":{"activated":true,"total_views":32,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.2 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil - PachaMamita Ecuador<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil\" \/>\n<meta property=\"og:description\" content=\"La Corte Interamericana de Derechos Humanos llegar\u00e1 en los pr\u00f3ximos d\u00edas a Ecuador. Durante su estad\u00eda visitar\u00e1 el pueblo originario kichwa de Sarayaku (Prov. de Pastaza) a partir del d\u00eda s\u00e1bado 21 de abril y luego celebrar\u00e1 del 23 al 27 de este mismo mes, en Guayaquil, su 45\u00ba Per\u00edodo Extraordinario de Sesiones . La [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/\" \/>\n<meta property=\"og:site_name\" content=\"PachaMamita Ecuador\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pachamamitaecu\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-18T07:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T15:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s400\/logo.jpg\" \/>\n<meta name=\"author\" content=\"PachaMamita EC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"PachaMamita EC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/\"},\"author\":{\"name\":\"PachaMamita EC\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\"},\"headline\":\"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil\",\"datePublished\":\"2012-04-18T07:57:00+00:00\",\"dateModified\":\"2023-03-01T15:27:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/\"},\"wordCount\":606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-9AYjgN9DNlM\\\/T45zpUbZMgI\\\/AAAAAAAAB74\\\/e7Qwjow7rZs\\\/s400\\\/logo.jpg\",\"articleSection\":[\"CONSUMO RESPONSABLE\",\"noticias\",\"sarayacu\",\"sarayaku\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/\",\"name\":\"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil - PachaMamita Ecuador\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-9AYjgN9DNlM\\\/T45zpUbZMgI\\\/AAAAAAAAB74\\\/e7Qwjow7rZs\\\/s400\\\/logo.jpg\",\"datePublished\":\"2012-04-18T07:57:00+00:00\",\"dateModified\":\"2023-03-01T15:27:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#primaryimage\",\"url\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-9AYjgN9DNlM\\\/T45zpUbZMgI\\\/AAAAAAAAB74\\\/e7Qwjow7rZs\\\/s400\\\/logo.jpg\",\"contentUrl\":\"http:\\\/\\\/2.bp.blogspot.com\\\/-9AYjgN9DNlM\\\/T45zpUbZMgI\\\/AAAAAAAAB74\\\/e7Qwjow7rZs\\\/s400\\\/logo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/2012\\\/04\\\/18\\\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#website\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"name\":\"PachaMamita Ecuador\",\"description\":\"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.\",\"publisher\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#organization\",\"name\":\"PachaMamita Ecuador\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/cropped-Diseno-sin-titulo-13.png\",\"width\":512,\"height\":512,\"caption\":\"PachaMamita Ecuador\"},\"image\":{\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pachamamitaecu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/#\\\/schema\\\/person\\\/e8b42afae2451fadab5e0295f02c4593\",\"name\":\"PachaMamita EC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/litespeed\\\/avatar\\\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103\",\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/litespeed\\\/avatar\\\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103\",\"contentUrl\":\"https:\\\/\\\/pachamamitaecu.org\\\/wp-content\\\/litespeed\\\/avatar\\\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103\",\"caption\":\"PachaMamita EC\"},\"url\":\"https:\\\/\\\/pachamamitaecu.org\\\/es_es\\\/author\\\/pachamamita-ec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil - PachaMamita Ecuador","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/","og_locale":"es_ES","og_type":"article","og_title":"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil","og_description":"La Corte Interamericana de Derechos Humanos llegar\u00e1 en los pr\u00f3ximos d\u00edas a Ecuador. Durante su estad\u00eda visitar\u00e1 el pueblo originario kichwa de Sarayaku (Prov. de Pastaza) a partir del d\u00eda s\u00e1bado 21 de abril y luego celebrar\u00e1 del 23 al 27 de este mismo mes, en Guayaquil, su 45\u00ba Per\u00edodo Extraordinario de Sesiones . La [...]","og_url":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/","og_site_name":"PachaMamita Ecuador","article_publisher":"https:\/\/www.facebook.com\/pachamamitaecu","article_published_time":"2012-04-18T07:57:00+00:00","article_modified_time":"2023-03-01T15:27:25+00:00","og_image":[{"url":"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s400\/logo.jpg","type":"","width":"","height":""}],"author":"PachaMamita EC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"PachaMamita EC","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#article","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/"},"author":{"name":"PachaMamita EC","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593"},"headline":"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil","datePublished":"2012-04-18T07:57:00+00:00","dateModified":"2023-03-01T15:27:25+00:00","mainEntityOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/"},"wordCount":606,"commentCount":0,"publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s400\/logo.jpg","articleSection":["CONSUMO RESPONSABLE","noticias","sarayacu","sarayaku"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/","url":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/","name":"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil - PachaMamita Ecuador","isPartOf":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#primaryimage"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#primaryimage"},"thumbnailUrl":"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s400\/logo.jpg","datePublished":"2012-04-18T07:57:00+00:00","dateModified":"2023-03-01T15:27:25+00:00","breadcrumb":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#primaryimage","url":"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s400\/logo.jpg","contentUrl":"http:\/\/2.bp.blogspot.com\/-9AYjgN9DNlM\/T45zpUbZMgI\/AAAAAAAAB74\/e7Qwjow7rZs\/s400\/logo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/pachamamitaecu.org\/es_es\/2012\/04\/18\/corte-interamericana-de-derechos-humanos-llega-a-sarayaku-y-luego-sesionara-en-guayaquil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/pachamamitaecu.org\/es_es\/"},{"@type":"ListItem","position":2,"name":"Corte Interamericana de Derechos Humanos llega a Sarayaku y luego sesionar\u00e1 en Guayaquil"}]},{"@type":"WebSite","@id":"https:\/\/pachamamitaecu.org\/es_es\/#website","url":"https:\/\/pachamamitaecu.org\/es_es\/","name":"PachaMamita Ecuador","description":"CULTURA. AGROECOLOG\u00cdA. TURISMO Y CONSUMO RESPONSABLE-ECUADOR.","publisher":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pachamamitaecu.org\/es_es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pachamamitaecu.org\/es_es\/#organization","name":"PachaMamita Ecuador","url":"https:\/\/pachamamitaecu.org\/es_es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/","url":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/uploads\/2024\/04\/cropped-Diseno-sin-titulo-13.png","width":512,"height":512,"caption":"PachaMamita Ecuador"},"image":{"@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pachamamitaecu"]},{"@type":"Person","@id":"https:\/\/pachamamitaecu.org\/es_es\/#\/schema\/person\/e8b42afae2451fadab5e0295f02c4593","name":"PachaMamita EC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pachamamitaecu.org\/wp-content\/litespeed\/avatar\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103","url":"https:\/\/pachamamitaecu.org\/wp-content\/litespeed\/avatar\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103","contentUrl":"https:\/\/pachamamitaecu.org\/wp-content\/litespeed\/avatar\/23494c9101089ad44ae88ce9d2f56aac.jpg?ver=1778561103","caption":"PachaMamita EC"},"url":"https:\/\/pachamamitaecu.org\/es_es\/author\/pachamamita-ec\/"}]}},"_links":{"self":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/comments?post=987"}],"version-history":[{"count":0,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/posts\/987\/revisions"}],"wp:attachment":[{"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/media?parent=987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/categories?post=987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachamamitaecu.org\/es_es\/wp-json\/wp\/v2\/tags?post=987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}